{"id":2339,"date":"2021-11-04T10:14:56","date_gmt":"2021-11-04T09:14:56","guid":{"rendered":"https:\/\/dialogbrhv.de\/?p=2339"},"modified":"2022-06-24T17:36:33","modified_gmt":"2022-06-24T15:36:33","slug":"veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr","status":"publish","type":"post","link":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/","title":{"rendered":"Veranstaltung : <BR>Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d <BR>am 06.11.2021 um 18.00 Uhr"},"content":{"rendered":"\n<p>Im Rahmen der diesj\u00e4hrigen Integrationswoche laden \u201cDialog \u2013 Verein f\u00fcr gleiche Rechte\u201d und der AK \u201cMigration und Fl\u00fcchtlinge\u201d zu einem \u201cGespr\u00e4ch mit Nachkommen von \u201cGastarbeiter*innen aus der T\u00fcrkei\u201d ein.<br \/>Die Veranstaltung findet statt am :\u00a0<strong>Samstag, den 06.11.2021 um 18.00 Uhr im Vereinshaus in der Hansastr. 2a.<\/strong><\/p>\n<p>1981 gr\u00fcndeten t\u00fcrkische \u201cGastarbeiter*innen\u201d den \u201cDemokratischen Arbeiterverein in Bremerhaven\u201d. Aus diesen Wurzeln entwickelte sich 1994 \u201cDialog \u2013 Verein f\u00fcr gleiche Rechte\u201d. In verschiedenen Gespr\u00e4chsrunden werden u.a. Mitglieder des Vereins von ihrem Leben und dem ihrer Eltern und Gro\u00dfeltern erz\u00e4hlen und von den Schwierigkeiten welche die 1.-3. Generation \u00fcberwinden musste. Auch Mitglieder vom Alevitischen Kulturverein, von der Alevitischen Jugend und vom Kurdisch-Deutschen Gemeinschaftsverein werden sich an den Gespr\u00e4chsrunden beteiligen. Denn neben Menschen, die zum Arbeiten nach Deutschland kamen, verlie\u00dfen auch Menschen die T\u00fcrkei, die dort verfolgt und unterdr\u00fcckt wurden.\u00a0<a href=\"https:\/\/xn--nord-sd-forum-1ob.de\/wp-content\/uploads\/2021\/11\/Einladung-06-11-um-18-00-Uhr-in-Hansastrasse-2a.pdf\">Einladung<\/a><\/p>\n<p><strong>F\u00fcr die Veranstaltung gilt die \u201e2\u202fG Regel\u201c: Zutritt zu \u00f6ffentlichen Innenr\u00e4umen gibt es nur f\u00fcr Geimpfte und Genesende. Auch bitten wir darum, sich f\u00fcr die Veranstaltung anzumelden!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen der diesj\u00e4hrigen Integrationswoche laden \u201cDialog \u2013 Verein f\u00fcr gleiche Rechte\u201d und der AK \u201cMigration und Fl\u00fcchtlinge\u201d zu einem<\/p>\n","protected":false},"author":1,"featured_media":2415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"template-fullwidth.php","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","inline_featured_image":false,"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr - Dialog - Verein f\u00fcr gleiche Rechte e.V.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr - Dialog - Verein f\u00fcr gleiche Rechte e.V.\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen der diesj\u00e4hrigen Integrationswoche laden \u201cDialog \u2013 Verein f\u00fcr gleiche Rechte\u201d und der AK \u201cMigration und Fl\u00fcchtlinge\u201d zu einem\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/\" \/>\n<meta property=\"og:site_name\" content=\"Dialog - Verein f\u00fcr gleiche Rechte e.V.\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-04T09:14:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-24T15:36:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rainer Piechura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"http:\/\/dialogbrhv.de\/#organization\",\"name\":\"DIALOG - Verein f\u00fcr gleiche Rechte e.V.\",\"url\":\"http:\/\/dialogbrhv.de\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/dialogbrhv.de\/#logo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2019\/09\/dialog_logo_v3.0_text_ausrichtungen_grundvorlage_dialog_normal_textstil1_17cm_stern_globus.svg_.png\",\"contentUrl\":\"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2019\/09\/dialog_logo_v3.0_text_ausrichtungen_grundvorlage_dialog_normal_textstil1_17cm_stern_globus.svg_.png\",\"width\":211,\"height\":214,\"caption\":\"DIALOG - Verein f\u00fcr gleiche Rechte e.V.\"},\"image\":{\"@id\":\"http:\/\/dialogbrhv.de\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/dialogbrhv.de\/#website\",\"url\":\"http:\/\/dialogbrhv.de\/\",\"name\":\"Dialog - Verein f\u00fcr gleiche Rechte e.V.\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\/\/dialogbrhv.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/dialogbrhv.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#primaryimage\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png\",\"contentUrl\":\"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png\",\"width\":450,\"height\":427},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#webpage\",\"url\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/\",\"name\":\"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr - Dialog - Verein f\u00fcr gleiche Rechte e.V.\",\"isPartOf\":{\"@id\":\"http:\/\/dialogbrhv.de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#primaryimage\"},\"datePublished\":\"2021-11-04T09:14:56+00:00\",\"dateModified\":\"2022-06-24T15:36:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"http:\/\/dialogbrhv.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#webpage\"},\"author\":{\"@id\":\"http:\/\/dialogbrhv.de\/#\/schema\/person\/8ce1189c87e7351176903d93a9d80b34\"},\"headline\":\"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr\",\"datePublished\":\"2021-11-04T09:14:56+00:00\",\"dateModified\":\"2022-06-24T15:36:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#webpage\"},\"wordCount\":190,\"publisher\":{\"@id\":\"http:\/\/dialogbrhv.de\/#organization\"},\"image\":{\"@id\":\"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png\",\"articleSection\":[\"Veranstaltungen\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/dialogbrhv.de\/#\/schema\/person\/8ce1189c87e7351176903d93a9d80b34\",\"name\":\"Rainer Piechura\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/dialogbrhv.de\/#personlogo\",\"inLanguage\":\"de-DE\",\"url\":\"https:\/\/dialogbrhv.de\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png\",\"contentUrl\":\"https:\/\/dialogbrhv.de\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png\",\"caption\":\"Rainer Piechura\"},\"url\":\"https:\/\/dialogbrhv.de\/index.php\/author\/rainer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr - Dialog - Verein f\u00fcr gleiche Rechte e.V.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/","og_locale":"de_DE","og_type":"article","og_title":"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr - Dialog - Verein f\u00fcr gleiche Rechte e.V.","og_description":"Im Rahmen der diesj\u00e4hrigen Integrationswoche laden \u201cDialog \u2013 Verein f\u00fcr gleiche Rechte\u201d und der AK \u201cMigration und Fl\u00fcchtlinge\u201d zu einem","og_url":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/","og_site_name":"Dialog - Verein f\u00fcr gleiche Rechte e.V.","article_published_time":"2021-11-04T09:14:56+00:00","article_modified_time":"2022-06-24T15:36:33+00:00","og_image":[{"width":450,"height":427,"url":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Rainer Piechura","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"http:\/\/dialogbrhv.de\/#organization","name":"DIALOG - Verein f\u00fcr gleiche Rechte e.V.","url":"http:\/\/dialogbrhv.de\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"http:\/\/dialogbrhv.de\/#logo","inLanguage":"de-DE","url":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2019\/09\/dialog_logo_v3.0_text_ausrichtungen_grundvorlage_dialog_normal_textstil1_17cm_stern_globus.svg_.png","contentUrl":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2019\/09\/dialog_logo_v3.0_text_ausrichtungen_grundvorlage_dialog_normal_textstil1_17cm_stern_globus.svg_.png","width":211,"height":214,"caption":"DIALOG - Verein f\u00fcr gleiche Rechte e.V."},"image":{"@id":"http:\/\/dialogbrhv.de\/#logo"}},{"@type":"WebSite","@id":"http:\/\/dialogbrhv.de\/#website","url":"http:\/\/dialogbrhv.de\/","name":"Dialog - Verein f\u00fcr gleiche Rechte e.V.","description":"","publisher":{"@id":"http:\/\/dialogbrhv.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/dialogbrhv.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"ImageObject","@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#primaryimage","inLanguage":"de-DE","url":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png","contentUrl":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png","width":450,"height":427},{"@type":"WebPage","@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#webpage","url":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/","name":"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr - Dialog - Verein f\u00fcr gleiche Rechte e.V.","isPartOf":{"@id":"http:\/\/dialogbrhv.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#primaryimage"},"datePublished":"2021-11-04T09:14:56+00:00","dateModified":"2022-06-24T15:36:33+00:00","breadcrumb":{"@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"http:\/\/dialogbrhv.de\/"},{"@type":"ListItem","position":2,"name":"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr"}]},{"@type":"Article","@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#article","isPartOf":{"@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#webpage"},"author":{"@id":"http:\/\/dialogbrhv.de\/#\/schema\/person\/8ce1189c87e7351176903d93a9d80b34"},"headline":"Veranstaltung : Nachkommen von Gastarbeiter*innen aus der T\u00fcrkei\u201d am 06.11.2021 um 18.00 Uhr","datePublished":"2021-11-04T09:14:56+00:00","dateModified":"2022-06-24T15:36:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#webpage"},"wordCount":190,"publisher":{"@id":"http:\/\/dialogbrhv.de\/#organization"},"image":{"@id":"https:\/\/dialogbrhv.de\/index.php\/2021\/11\/04\/veranstaltung-nachkommen-von-gastarbeiterinnen-aus-der-tuerkei-am-06-11-2021-um-18-00-uhr\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png","articleSection":["Veranstaltungen"],"inLanguage":"de-DE"},{"@type":"Person","@id":"http:\/\/dialogbrhv.de\/#\/schema\/person\/8ce1189c87e7351176903d93a9d80b34","name":"Rainer Piechura","image":{"@type":"ImageObject","@id":"http:\/\/dialogbrhv.de\/#personlogo","inLanguage":"de-DE","url":"https:\/\/dialogbrhv.de\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","contentUrl":"https:\/\/dialogbrhv.de\/wp-content\/plugins\/wp-user-avatar\/deprecated\/wp-user-avatar\/images\/wpua-96x96.png","caption":"Rainer Piechura"},"url":"https:\/\/dialogbrhv.de\/index.php\/author\/rainer\/"}]}},"jetpack_featured_media_url":"https:\/\/dialogbrhv.de\/wp-content\/uploads\/2021\/11\/Dialog-Nord-Sued-Forum-Logo.png","jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/posts\/2339"}],"collection":[{"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/comments?post=2339"}],"version-history":[{"count":5,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/posts\/2339\/revisions"}],"predecessor-version":[{"id":2444,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/posts\/2339\/revisions\/2444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/media\/2415"}],"wp:attachment":[{"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/media?parent=2339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/categories?post=2339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dialogbrhv.de\/index.php\/wp-json\/wp\/v2\/tags?post=2339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}